{"id":9303,"date":"2026-02-02T11:23:36","date_gmt":"2026-02-02T03:23:36","guid":{"rendered":"https:\/\/www.packqc.com\/applications\/ink-rub-test\/"},"modified":"2026-03-16T11:32:31","modified_gmt":"2026-03-16T03:32:31","slug":"ink-rub-test","status":"publish","type":"applications","link":"https:\/\/www.packqc.com\/fr\/applications\/ink-rub-test\/","title":{"rendered":"Test de frottement de l'encre sur les emballages et les \u00e9tiquettes - ASTM D5264"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Les emballages imprim\u00e9s, les \u00e9tiquettes et les graphiques commerciaux sont soumis \u00e0 une usure importante pendant le stockage, l'exp\u00e9dition et la manutention. Pour garantir leur durabilit\u00e9, il faut disposer de m\u00e9thodes d'\u00e9valuation fiables. L'une des techniques les plus largement reconnues est le <strong data-start=\"672\" data-end=\"688\">test de frottement d&#039;encre<\/strong>, Le test de frottement de l'encre est un moyen normalis\u00e9 de mesurer la r\u00e9sistance \u00e0 l'abrasion des mat\u00e9riaux imprim\u00e9s. Cet article pr\u00e9sente le test de frottement de l'encre, explique la proc\u00e9dure ASTM D5264 et met en \u00e9vidence la mani\u00e8re dont un test de frottement de l'encre peut \u00eatre r\u00e9alis\u00e9. <strong data-start=\"860\" data-end=\"885\">testeur de r\u00e9sistance au frottement<\/strong> garantit des r\u00e9sultats coh\u00e9rents.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Pourquoi le test du frottement de l'encre est-il important pour l'impression et l'emballage ?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">L'abrasion est l'une des causes les plus courantes de la d\u00e9gradation des impressions. Lors du transport et de l'utilisation, le frottement peut entra\u00eener des taches, une d\u00e9coloration ou un transfert de l'encre, ce qui se traduit par :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>R\u00e9duction de l'apparence et de la lisibilit\u00e9 de la marque<\/li>\n\n\n\n<li>Insatisfaction des clients en raison d'une mauvaise pr\u00e9sentation des produits<\/li>\n\n\n\n<li>Questions de conformit\u00e9 dans les secteurs r\u00e9glement\u00e9s o\u00f9 la clart\u00e9 de l'\u00e9tiquetage est essentielle<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">En menant l'enqu\u00eate <strong data-start=\"1341\" data-end=\"1373\">test de r\u00e9sistance \u00e0 l'abrasion de l'encre<\/strong>, Les fabricants peuvent ainsi \u00e9valuer si leurs mat\u00e9riaux imprim\u00e9s peuvent r\u00e9sister \u00e0 ces conditions r\u00e9elles. Cela garantit \u00e0 la fois la qualit\u00e9 du produit et la confiance du consommateur.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">ASTM D5264 et son r\u00f4le dans les tests de r\u00e9sistance \u00e0 l'abrasion des encres<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La ligne directrice la plus largement r\u00e9f\u00e9renc\u00e9e pour cette \u00e9valuation est la suivante <strong data-start=\"1659\" data-end=\"1767\"><a href=\"https:\/\/www.packqc.com\/fr\/standard\/astm-d5264\/\">ASTM D5264<\/a> - Pratique courante pour la r\u00e9sistance \u00e0 l'abrasion des mat\u00e9riaux imprim\u00e9s par le test de frottement Sutherland<\/strong>. Cette norme d\u00e9crit comment mesurer la durabilit\u00e9 de l'impression \u00e0 l'aide de cycles de frottement contr\u00f4l\u00e9s entre un sp\u00e9cimen et une surface r\u00e9ceptrice.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Principaux faits marquants <a href=\"https:\/\/store.astm.org\/d5264-98r19.html\" rel=\"nofollow noopener\" target=\"_blank\">ASTM D5264<\/a> inclure:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong data-start=\"1945\" data-end=\"1959\">Configuration du test<\/strong>: Le mat\u00e9riel imprim\u00e9 est mont\u00e9 sur un tampon en caoutchouc, tandis qu'un r\u00e9cepteur est fix\u00e9 \u00e0 un poids de 2 lb (0,91 kg) ou 4 lb (1,82 kg).<\/li>\n\n\n\n<li><strong data-start=\"2085\" data-end=\"2098\">Fonctionnement<\/strong>: Le r\u00e9cepteur se d\u00e9place d'avant en arri\u00e8re sur l'impression pendant un nombre pr\u00e9d\u00e9fini de coups. Chaque course correspond \u00e0 un cycle complet.<\/li>\n\n\n\n<li><strong data-start=\"2220\" data-end=\"2234\">L'\u00e9valuation<\/strong>: Apr\u00e8s le test, l'impression est inspect\u00e9e pour d\u00e9tecter toute d\u00e9gradation visible et le r\u00e9cepteur est analys\u00e9 pour le transfert d'encre.<\/li>\n\n\n\n<li><strong data-start=\"2351\" data-end=\"2367\">Applications<\/strong>: Cette pratique convient aux encres, aux rev\u00eatements, aux stratifi\u00e9s et aux substrats et peut \u00eatre adapt\u00e9e \u00e0 l'\u00e9tude des effets des produits tels que le contact avec les d\u00e9tergents ou les aliments.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Cette m\u00e9thode offre un moyen reproductible de comparer la r\u00e9sistance \u00e0 l'abrasion dans des conditions contr\u00f4l\u00e9es, ce qui permet aux acheteurs et aux fournisseurs de se mettre d'accord sur les normes de performance.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Applications du test de r\u00e9sistance \u00e0 l'abrasion des encres<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Le test de frottement de l'encre est largement utilis\u00e9 dans tous les secteurs d'activit\u00e9 :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong data-start=\"3661\" data-end=\"3674\">Conditionnement<\/strong>: Veiller \u00e0 ce que les emballages des produits alimentaires, des boissons et des produits pharmaceutiques conservent des \u00e9tiquettes claires.<\/li>\n\n\n\n<li><strong data-start=\"3754\" data-end=\"3779\">Textiles et rev\u00eatements<\/strong>: V\u00e9rification de la durabilit\u00e9 des motifs imprim\u00e9s sur des tissus ou des surfaces enduites.<\/li>\n\n\n\n<li><strong data-start=\"3859\" data-end=\"3886\">Adh\u00e9sifs et stratifi\u00e9s<\/strong>: \u00c9valuation de la r\u00e9sistance aux \u00e9raflures lorsque des mat\u00e9riaux stratifi\u00e9s peuvent frotter l'un contre l'autre.<\/li>\n\n\n\n<li><strong data-start=\"3962\" data-end=\"3993\">Agences d'inspection de la qualit\u00e9<\/strong>: Fournir des r\u00e9sultats normalis\u00e9s, pouvant faire l'objet d'un rapport, pour les audits de conformit\u00e9.<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>Les emballages imprim\u00e9s, les \u00e9tiquettes et les supports graphiques commerciaux sont soumis \u00e0 une usure importante pendant le stockage, le transport et la manutention. Pour garantir leur durabilit\u00e9, il est n\u00e9cessaire de disposer de m\u00e9thodes d\u2019\u00e9valuation fiables. L'une des techniques les plus largement reconnues est le test de frottement de l'encre, une m\u00e9thode normalis\u00e9e permettant de mesurer la r\u00e9sistance \u00e0 l'abrasion des supports imprim\u00e9s. Cet article pr\u00e9sente le test de frottement de l'encre, explique la proc\u00e9dure ASTM D5264, [\u2026]<\/p>","protected":false},"featured_media":2952,"parent":0,"template":"","meta":{"_acf_changed":true,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""}}},"class_list":["post-9303","applications","type-applications","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.packqc.com\/fr\/wp-json\/wp\/v2\/applications\/9303","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.packqc.com\/fr\/wp-json\/wp\/v2\/applications"}],"about":[{"href":"https:\/\/www.packqc.com\/fr\/wp-json\/wp\/v2\/types\/applications"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.packqc.com\/fr\/wp-json\/wp\/v2\/media\/2952"}],"wp:attachment":[{"href":"https:\/\/www.packqc.com\/fr\/wp-json\/wp\/v2\/media?parent=9303"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}